{"id":641,"date":"2015-05-27T14:30:36","date_gmt":"2015-05-27T13:30:36","guid":{"rendered":"http:\/\/golf.piresgoncalves.net\/?p=641"},"modified":"2015-05-27T14:30:36","modified_gmt":"2015-05-27T13:30:36","slug":"torneio-da-sardinhada-2015","status":"publish","type":"post","link":"https:\/\/clubegolfecaixa.pt\/golfe\/torneio-da-sardinhada-2015\/","title":{"rendered":"Torneio da sardinhada 2015"},"content":{"rendered":"<p>Como consta do planeamento das nossas actividades para o corrente ano, vamos disputar o tradicional <strong>Torneio da Sardinhada<\/strong> no pr\u00f3ximo dia <strong>10 de Junho<\/strong> no campo dos Salgados, cujo Regulamento se anexa.<\/p>\n<blockquote><p>Agradecemos que as inscri\u00e7\u00f5es sejam efectuadas para o endere\u00e7o do Clube <a href=\"mail:\/\/golfecgd@gmail.com\" target=\"_blank\">golfe cgd<\/a>\u00a0at\u00e9 \u00e0 quinta feira, dia 4 de Junho.<\/p><\/blockquote>\n<p>Quem n\u00e3o tiver par e queira participar deve inscrever-se que o Clube tratar\u00e1 de arranjar parceiro.<\/p>\n<p>Por quest\u00f5es de qualidade do servi\u00e7o de restaura\u00e7\u00e3o, a participa\u00e7\u00e3o \u00e9 limitada a 60 jogadores (30 pares), que ser\u00e3o aceites por ordem de inscri\u00e7\u00e3o.<\/p>\n<p>At\u00e9 l\u00e1, treinem muito e, sobretudo, divirtam-se<\/p>\n<a href='\/events\/torneio-da-sardinhada-2015-2\/' class='big-button bigblue' target=\"_blank\">Inscri\u00e7\u00e3o no Torneio<\/a>\n<a href='\/torneio-da-sardinhada-2015_doc' class='big-button bigorange' target=\"_blank\">Informa\u00e7\u00e3o sobre o Torneio<\/a>\n","protected":false},"excerpt":{"rendered":"<p>Como consta do planeamento das nossas actividades para o corrente ano, vamos disputar o tradicional Torneio da Sardinhada no pr\u00f3ximo dia 10 de Junho no campo dos Salgados, cujo Regulamento se anexa. Agradecemos que as inscri\u00e7\u00f5es sejam efectuadas para o endere\u00e7o do Clube golfe cgd\u00a0at\u00e9 \u00e0 quinta feira, dia 4 de Junho. Quem n\u00e3o tiver [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/posts\/641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/comments?post=641"}],"version-history":[{"count":0,"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/posts\/641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/media\/132"}],"wp:attachment":[{"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/media?parent=641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/categories?post=641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubegolfecaixa.pt\/golfe\/wp-json\/wp\/v2\/tags?post=641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}